{"id":224,"date":"2021-08-24T07:00:00","date_gmt":"2021-08-24T05:00:00","guid":{"rendered":"https:\/\/www.buehnen.de\/blog\/?p=224"},"modified":"2021-08-18T11:25:34","modified_gmt":"2021-08-18T09:25:34","slug":"reaktive-schmelzklebstoffe-die-spezialisten","status":"publish","type":"post","link":"https:\/\/www.buehnen.de\/blog\/reaktive-schmelzklebstoffe-die-spezialisten\/","title":{"rendered":"Reaktive Schmelzklebstoffe &#8211; Die Spezialisten"},"content":{"rendered":"\n<p><em>Reaktive Schmelzklebstoffe im B\u00dcHNEN Portfolio sind auf der Basis von Polyurethan (PUR) und Polyolefin (POR). Diese Polymere reagieren bei der Anwendung mit Luftfeuchtigkeit und durch Erw\u00e4rmen zu einem vernetzten Polymer.<\/em><\/p>\n\n\n\n<p>In unserem Glossar finden Sie\u00a0<strong>Fachbegriffe<\/strong>\u00a0aus der Klebstoffwelt\u00a0<strong>verst\u00e4ndlich erkl\u00e4rt<\/strong>.<\/p>\n\n\n\n<p>Von stark zunehmender Bedeutung sind die reaktiven Schmelzklebstoffe auf\u00a0<strong>Polyurethan- und Polyolefin-Basis.<\/strong>\u00a0Mit ihnen lassen sich konstruktive Verbindungen erzielen. Prinzip dieser feuchtigkeitsh\u00e4rtenden Schmelzklebstoffe ist ein zweistufiger Abbindemechanismus.<\/p>\n\n\n\n<p>Auf diese Weise k\u00f6nnen au\u00dfergew\u00f6hnlich hohe Temperaturbest\u00e4ndigkeiten bei gleichzeitig guter K\u00e4lteflexibilit\u00e4t und einer Resistenz gegen eine Vielzahl von Chemikalien erreicht werden. Standard PUR-Hotmelt mit einem MDI-Gehalt > als 0,1 % sind kennzeichnungspflichtig.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.buehnen.de\/service\/glossar\/reaktiver-schmelzklebstoff\">Eine Erkl\u00e4rung mit Darstellung der Vorteile und Lieferformen finden Sie in unserem Glossar.<\/a><\/p>\n\n\n\n<p>Reaktive Schmelzklebstoffe werden h\u00e4ufig im Automobilbereich und in der Bauindustrie eingesetzt.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"574\" src=\"https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2021\/08\/HB-720-K-Teppich.jpg?resize=860%2C574&#038;ssl=1\" alt=\"\" class=\"wp-image-225\" srcset=\"https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2021\/08\/HB-720-K-Teppich-scaled.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2021\/08\/HB-720-K-Teppich-scaled.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2021\/08\/HB-720-K-Teppich-scaled.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2021\/08\/HB-720-K-Teppich-scaled.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2021\/08\/HB-720-K-Teppich-scaled.jpg?resize=2048%2C1365&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2021\/08\/HB-720-K-Teppich-scaled.jpg?w=1720&amp;ssl=1 1720w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/figure>\n\n\n\n<p>Hohe Temperaturbest\u00e4ndigkeit in der K\u00e4lte, wie in der W\u00e4rme erm\u00f6glichen z. B. den Einsatz von reaktiven Schmelzklebstoffen in der Automobilindustrie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Arbeitsprinzip der feuchtigkeitsh\u00e4rtenden Schmelzklebstoffe wird im Glossar erkl\u00e4rt.<\/p>\n","protected":false},"author":2,"featured_media":158,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[31],"tags":[33,20,55],"class_list":["post-224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-glossar","tag-glossar","tag-produkte","tag-reaktive-klebstoffe"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2021\/07\/Fachwort-Dienstag2.jpg?fit=900%2C250&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/posts\/224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/comments?post=224"}],"version-history":[{"count":1,"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/posts\/224\/revisions"}],"predecessor-version":[{"id":226,"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/posts\/224\/revisions\/226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/media\/158"}],"wp:attachment":[{"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/media?parent=224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/categories?post=224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/tags?post=224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}