{"id":2656,"date":"2024-11-12T09:36:02","date_gmt":"2024-11-12T08:36:02","guid":{"rendered":"https:\/\/www.buehnen.de\/blog\/?p=2656"},"modified":"2024-11-13T08:43:06","modified_gmt":"2024-11-13T07:43:06","slug":"buehnen-in-den-top-5-bremer-arbeitgeber","status":"publish","type":"post","link":"https:\/\/www.buehnen.de\/blog\/buehnen-in-den-top-5-bremer-arbeitgeber\/","title":{"rendered":"B\u00dcHNEN in den TOP 5 Bremer Arbeitgeber"},"content":{"rendered":"\n<p>Wie die&nbsp;<a href=\"https:\/\/www.t-online.de\/region\/bremen\/id_100526974\/bremen-die-besten-arbeitgeber-laut-kununu-bewertungen-ranking.html\">T-Online Homepage<\/a>&nbsp;berichtete, wurden in Bremen die Top-Arbeitgeber bewertet. <strong>In der Kategorie der kleinen und mittelst\u00e4ndischen Unternehmen (KMU)<\/strong> hat es B\u00dcHNEN mit einer&nbsp;<a href=\"https:\/\/www.kununu.com\/de\/buehnen1\/kommentare?sort=newest\">kununu-Bewertung<\/a>&nbsp;von 4,1 (aktueller Wert sogar 4,2) auf Platz 5 geschafft.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"176\" src=\"https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2024\/11\/Bild1.jpg?resize=860%2C176&#038;ssl=1\" alt=\"\" class=\"wp-image-2667\" style=\"width:600px\" srcset=\"https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2024\/11\/Bild1.jpg?resize=1024%2C210&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2024\/11\/Bild1.jpg?resize=300%2C62&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2024\/11\/Bild1.jpg?resize=768%2C158&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2024\/11\/Bild1.jpg?resize=1536%2C315&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2024\/11\/Bild1.jpg?w=1890&amp;ssl=1 1890w, https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2024\/11\/Bild1.jpg?w=1720&amp;ssl=1 1720w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/figure>\n<\/div>\n\n\n<p><strong>B\u00dcHNEN ist seit 2013 auf der Bewertungsplattform kununu pr\u00e4sent, die Basis f\u00fcr diese Auszeichnung.<\/strong> Seit 2022 verleiht kununu den &#8222;Top Company Award&#8220; an Unternehmen mit besonders guten Bewertungen. <strong>Wir sind stolz darauf, zu diesen Arbeitgebern zu geh\u00f6ren und diesen Award erhalten zu haben.<\/strong><\/p>\n\n\n\n<p>Um den <strong>Top Company Award<\/strong> zu erhalten, m\u00fcssen Unternehmen bestimmte Kriterien erf\u00fcllen: Ein Score von mindestens 3,8 Sternen, mindestens sieben Bewertungen insgesamt sowie mindestens zwei Bewertungen aus den letzten 12 Monaten sind erforderlich. Nur <strong>5 Prozent der Unternehmen qualifizieren sich<\/strong>, was die Auszeichnung umso bedeutender macht. <strong>Mit einem Score von 4,2 Sternen, 51 Bewertungen und einer Weiterempfehlungsrate von 79 Prozent<\/strong> freuen wir uns, eines dieser ausgezeichneten Unternehmen zu sein.<\/p>\n\n\n\n<p>F\u00fcr uns best\u00e4tigt dieser Award unser Engagement f\u00fcr die Zufriedenheit und das Wohlbefinden unserer Mitarbeitenden. Wir sch\u00e4tzen das Feedback \u2013 auch das kritische \u2013 und setzen uns aktiv daf\u00fcr ein, ein Arbeitsumfeld zu schaffen, das inspiriert, f\u00f6rdert und sich kontinuierlich weiterentwickelt.<\/p>\n\n\n\n<p><strong>Um die W\u00fcnsche und Bed\u00fcrfnisse unserer Mitarbeitenden regelm\u00e4\u00dfig zu erfassen, f\u00fchren wir j\u00e4hrlich interne Mitarbeiterbefragungen durch.<\/strong> Diese werden anonymisiert, um auch Anliegen au\u00dferhalb des \u00fcblichen Jahresgespr\u00e4chs ansprechen zu k\u00f6nnen.<\/p>\n\n\n\n<p>Die zahlreichen Benefits \u2013 wie <strong>Firmenfahrr\u00e4der, Fitnessangebote, professionelle Arbeitskleidung, Lades\u00e4ulen f\u00fcr E-Autos, gemeinsame Events<\/strong> und vieles mehr \u2013 tragen zur Zufriedenheit bei. Aber auch kritisches Feedback verhallt bei uns nicht ungeh\u00f6rt: Die T\u00fcren der Gesch\u00e4ftsf\u00fchrung stehen jederzeit offen.<\/p>\n\n\n\n<p>Seit der Einf\u00fchrung der informellen Anrede &#8222;Du&#8220; im Jahr 2021 ist es noch einfacher, in freundschaftlichem Rahmen Feedback auszutauschen und eine offene Gespr\u00e4chskultur zu pflegen. <strong>Wir sind motiviert, auch in Zukunft ein Top-Arbeitgeber zu bleiben.<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"735\" height=\"662\" src=\"https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2024\/11\/Kununu-Top4.jpg?resize=735%2C662&#038;ssl=1\" alt=\"\" class=\"wp-image-2668\" srcset=\"https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2024\/11\/Kununu-Top4.jpg?w=735&amp;ssl=1 735w, https:\/\/i0.wp.com\/www.buehnen.de\/blog\/wp-content\/uploads\/2024\/11\/Kununu-Top4.jpg?resize=300%2C270&amp;ssl=1 300w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Wir freuen uns riesig: B\u00dcHNEN wurde als Top-Arbeitgeber in Bremen ausgezeichnet!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,9,95],"tags":[122,38],"class_list":["post-2656","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-backstage","category-jobs","tag-122","tag-backstage"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/posts\/2656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/comments?post=2656"}],"version-history":[{"count":3,"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/posts\/2656\/revisions"}],"predecessor-version":[{"id":2669,"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/posts\/2656\/revisions\/2669"}],"wp:attachment":[{"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/media?parent=2656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/categories?post=2656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buehnen.de\/blog\/wp-json\/wp\/v2\/tags?post=2656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}